
{"id":24337,"date":"2021-12-02T11:34:53","date_gmt":"2021-12-02T11:34:53","guid":{"rendered":"https:\/\/www.nuevapescanova.com\/portfolio-item\/campana-de-navidad-2021\/"},"modified":"2021-12-20T11:52:29","modified_gmt":"2021-12-20T11:52:29","slug":"campana-de-navidad-2021","status":"publish","type":"portfolio","link":"https:\/\/www.nuevapescanova.com\/en\/portfolio-item\/campana-de-navidad-2021\/","title":{"rendered":"Christmas Campaign 2021"},"content":{"rendered":"<p><a href=\"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/CAMPANA_.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-24160 size-full\" src=\"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/CAMPANA_.jpg\" alt=\"\" width=\"787\" height=\"1134\" srcset=\"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/CAMPANA_.jpg 787w, https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/CAMPANA_-208x300.jpg 208w, https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/CAMPANA_-768x1107.jpg 768w, https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/CAMPANA_-101x146.jpg 101w, https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/CAMPANA_-35x50.jpg 35w, https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/CAMPANA_-52x75.jpg 52w\" sizes=\"auto, (max-width: 787px) 100vw, 787px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":24160,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"portfolio-types":[135],"class_list":["post-24337","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-types-campanas-de-publicidad-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Christmas Campaign 2021 - Nueva Pescanova<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nuevapescanova.com\/en\/portfolio-item\/campana-de-navidad-2021\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Christmas Campaign 2021 - Nueva Pescanova\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nuevapescanova.com\/en\/portfolio-item\/campana-de-navidad-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Nueva Pescanova\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-20T11:52:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/CAMPANA_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"787\" \/>\n\t<meta property=\"og:image:height\" content=\"1134\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@PescanovaCorp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.nuevapescanova.com\/en\/portfolio-item\/campana-de-navidad-2021\/\",\"url\":\"https:\/\/www.nuevapescanova.com\/en\/portfolio-item\/campana-de-navidad-2021\/\",\"name\":\"Christmas Campaign 2021 - Nueva Pescanova\",\"isPartOf\":{\"@id\":\"https:\/\/www.nuevapescanova.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.nuevapescanova.com\/en\/portfolio-item\/campana-de-navidad-2021\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.nuevapescanova.com\/en\/portfolio-item\/campana-de-navidad-2021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/CAMPANA_.jpg\",\"datePublished\":\"2021-12-02T11:34:53+00:00\",\"dateModified\":\"2021-12-20T11:52:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.nuevapescanova.com\/en\/portfolio-item\/campana-de-navidad-2021\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.nuevapescanova.com\/en\/portfolio-item\/campana-de-navidad-2021\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.nuevapescanova.com\/en\/portfolio-item\/campana-de-navidad-2021\/#primaryimage\",\"url\":\"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/CAMPANA_.jpg\",\"contentUrl\":\"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/CAMPANA_.jpg\",\"width\":787,\"height\":1134},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.nuevapescanova.com\/en\/portfolio-item\/campana-de-navidad-2021\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.nuevapescanova.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Christmas Campaign 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nuevapescanova.com\/#website\",\"url\":\"https:\/\/www.nuevapescanova.com\/\",\"name\":\"Nueva Pescanova\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.nuevapescanova.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.nuevapescanova.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.nuevapescanova.com\/#organization\",\"name\":\"Nueva Pescanova\",\"url\":\"https:\/\/www.nuevapescanova.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.nuevapescanova.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2023\/06\/Logo-Grupo-Nueva-Pescanova.jpg\",\"contentUrl\":\"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2023\/06\/Logo-Grupo-Nueva-Pescanova.jpg\",\"width\":800,\"height\":398,\"caption\":\"Nueva Pescanova\"},\"image\":{\"@id\":\"https:\/\/www.nuevapescanova.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/PescanovaCorp\",\"https:\/\/www.linkedin.com\/company\/nuevapescanova\/?originalSubdomain=es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Christmas Campaign 2021 - Nueva Pescanova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nuevapescanova.com\/en\/portfolio-item\/campana-de-navidad-2021\/","og_locale":"en_US","og_type":"article","og_title":"Christmas Campaign 2021 - Nueva Pescanova","og_url":"https:\/\/www.nuevapescanova.com\/en\/portfolio-item\/campana-de-navidad-2021\/","og_site_name":"Nueva Pescanova","article_modified_time":"2021-12-20T11:52:29+00:00","og_image":[{"width":787,"height":1134,"url":"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/CAMPANA_.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@PescanovaCorp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.nuevapescanova.com\/en\/portfolio-item\/campana-de-navidad-2021\/","url":"https:\/\/www.nuevapescanova.com\/en\/portfolio-item\/campana-de-navidad-2021\/","name":"Christmas Campaign 2021 - Nueva Pescanova","isPartOf":{"@id":"https:\/\/www.nuevapescanova.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nuevapescanova.com\/en\/portfolio-item\/campana-de-navidad-2021\/#primaryimage"},"image":{"@id":"https:\/\/www.nuevapescanova.com\/en\/portfolio-item\/campana-de-navidad-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/CAMPANA_.jpg","datePublished":"2021-12-02T11:34:53+00:00","dateModified":"2021-12-20T11:52:29+00:00","breadcrumb":{"@id":"https:\/\/www.nuevapescanova.com\/en\/portfolio-item\/campana-de-navidad-2021\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nuevapescanova.com\/en\/portfolio-item\/campana-de-navidad-2021\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nuevapescanova.com\/en\/portfolio-item\/campana-de-navidad-2021\/#primaryimage","url":"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/CAMPANA_.jpg","contentUrl":"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/CAMPANA_.jpg","width":787,"height":1134},{"@type":"BreadcrumbList","@id":"https:\/\/www.nuevapescanova.com\/en\/portfolio-item\/campana-de-navidad-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.nuevapescanova.com\/en\/"},{"@type":"ListItem","position":2,"name":"Christmas Campaign 2021"}]},{"@type":"WebSite","@id":"https:\/\/www.nuevapescanova.com\/#website","url":"https:\/\/www.nuevapescanova.com\/","name":"Nueva Pescanova","description":"","publisher":{"@id":"https:\/\/www.nuevapescanova.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nuevapescanova.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.nuevapescanova.com\/#organization","name":"Nueva Pescanova","url":"https:\/\/www.nuevapescanova.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nuevapescanova.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2023\/06\/Logo-Grupo-Nueva-Pescanova.jpg","contentUrl":"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2023\/06\/Logo-Grupo-Nueva-Pescanova.jpg","width":800,"height":398,"caption":"Nueva Pescanova"},"image":{"@id":"https:\/\/www.nuevapescanova.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/PescanovaCorp","https:\/\/www.linkedin.com\/company\/nuevapescanova\/?originalSubdomain=es"]}]}},"_links":{"self":[{"href":"https:\/\/www.nuevapescanova.com\/en\/wp-json\/wp\/v2\/portfolio\/24337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nuevapescanova.com\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.nuevapescanova.com\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.nuevapescanova.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nuevapescanova.com\/en\/wp-json\/wp\/v2\/comments?post=24337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nuevapescanova.com\/en\/wp-json\/wp\/v2\/media\/24160"}],"wp:attachment":[{"href":"https:\/\/www.nuevapescanova.com\/en\/wp-json\/wp\/v2\/media?parent=24337"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/www.nuevapescanova.com\/en\/wp-json\/wp\/v2\/portfolio-types?post=24337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}