
{"id":24346,"date":"2021-12-20T11:50:27","date_gmt":"2021-12-20T11:50:27","guid":{"rendered":"https:\/\/www.nuevapescanova.com\/portfolio-item\/campana-navidad-2021-2\/"},"modified":"2021-12-20T11:54:03","modified_gmt":"2021-12-20T11:54:03","slug":"campana-navidad-2021-2","status":"publish","type":"portfolio","link":"https:\/\/www.nuevapescanova.com\/fr\/portfolio-item\/campana-navidad-2021-2\/","title":{"rendered":"Campagne de N\u00f6el 2021 (2)"},"content":{"rendered":"<p><a href=\"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/Campana-2021.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-24201\" src=\"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/Campana-2021.jpg\" alt=\"\" width=\"1181\" height=\"976\" srcset=\"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/Campana-2021.jpg 1181w, https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/Campana-2021-300x248.jpg 300w, https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/Campana-2021-768x635.jpg 768w, https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/Campana-2021-177x146.jpg 177w, https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/Campana-2021-50x41.jpg 50w, https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/Campana-2021-91x75.jpg 91w\" sizes=\"auto, (max-width: 1181px) 100vw, 1181px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":24201,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"portfolio-types":[136],"class_list":["post-24346","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-types-campanas-de-publicidad-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Campagne de N\u00f6el 2021 (2) - Nueva Pescanova<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nuevapescanova.com\/fr\/portfolio-item\/campana-navidad-2021-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campagne de N\u00f6el 2021 (2) - Nueva Pescanova\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nuevapescanova.com\/fr\/portfolio-item\/campana-navidad-2021-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Nueva Pescanova\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-20T11:54:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/Campana-2021.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1181\" \/>\n\t<meta property=\"og:image:height\" content=\"976\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@PescanovaCorp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.nuevapescanova.com\/fr\/portfolio-item\/campana-navidad-2021-2\/\",\"url\":\"https:\/\/www.nuevapescanova.com\/fr\/portfolio-item\/campana-navidad-2021-2\/\",\"name\":\"Campagne de N\u00f6el 2021 (2) - Nueva Pescanova\",\"isPartOf\":{\"@id\":\"https:\/\/www.nuevapescanova.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.nuevapescanova.com\/fr\/portfolio-item\/campana-navidad-2021-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.nuevapescanova.com\/fr\/portfolio-item\/campana-navidad-2021-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/Campana-2021.jpg\",\"datePublished\":\"2021-12-20T11:50:27+00:00\",\"dateModified\":\"2021-12-20T11:54:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.nuevapescanova.com\/fr\/portfolio-item\/campana-navidad-2021-2\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.nuevapescanova.com\/fr\/portfolio-item\/campana-navidad-2021-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.nuevapescanova.com\/fr\/portfolio-item\/campana-navidad-2021-2\/#primaryimage\",\"url\":\"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/Campana-2021.jpg\",\"contentUrl\":\"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/Campana-2021.jpg\",\"width\":1181,\"height\":976},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.nuevapescanova.com\/fr\/portfolio-item\/campana-navidad-2021-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.nuevapescanova.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campagne de N\u00f6el 2021 (2)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nuevapescanova.com\/#website\",\"url\":\"https:\/\/www.nuevapescanova.com\/\",\"name\":\"Nueva Pescanova\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.nuevapescanova.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.nuevapescanova.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.nuevapescanova.com\/#organization\",\"name\":\"Nueva Pescanova\",\"url\":\"https:\/\/www.nuevapescanova.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.nuevapescanova.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2023\/06\/Logo-Grupo-Nueva-Pescanova.jpg\",\"contentUrl\":\"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2023\/06\/Logo-Grupo-Nueva-Pescanova.jpg\",\"width\":800,\"height\":398,\"caption\":\"Nueva Pescanova\"},\"image\":{\"@id\":\"https:\/\/www.nuevapescanova.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/PescanovaCorp\",\"https:\/\/www.linkedin.com\/company\/nuevapescanova\/?originalSubdomain=es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campagne de N\u00f6el 2021 (2) - Nueva Pescanova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nuevapescanova.com\/fr\/portfolio-item\/campana-navidad-2021-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Campagne de N\u00f6el 2021 (2) - Nueva Pescanova","og_url":"https:\/\/www.nuevapescanova.com\/fr\/portfolio-item\/campana-navidad-2021-2\/","og_site_name":"Nueva Pescanova","article_modified_time":"2021-12-20T11:54:03+00:00","og_image":[{"width":1181,"height":976,"url":"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/Campana-2021.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@PescanovaCorp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.nuevapescanova.com\/fr\/portfolio-item\/campana-navidad-2021-2\/","url":"https:\/\/www.nuevapescanova.com\/fr\/portfolio-item\/campana-navidad-2021-2\/","name":"Campagne de N\u00f6el 2021 (2) - Nueva Pescanova","isPartOf":{"@id":"https:\/\/www.nuevapescanova.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nuevapescanova.com\/fr\/portfolio-item\/campana-navidad-2021-2\/#primaryimage"},"image":{"@id":"https:\/\/www.nuevapescanova.com\/fr\/portfolio-item\/campana-navidad-2021-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/Campana-2021.jpg","datePublished":"2021-12-20T11:50:27+00:00","dateModified":"2021-12-20T11:54:03+00:00","breadcrumb":{"@id":"https:\/\/www.nuevapescanova.com\/fr\/portfolio-item\/campana-navidad-2021-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nuevapescanova.com\/fr\/portfolio-item\/campana-navidad-2021-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.nuevapescanova.com\/fr\/portfolio-item\/campana-navidad-2021-2\/#primaryimage","url":"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/Campana-2021.jpg","contentUrl":"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2021\/12\/Campana-2021.jpg","width":1181,"height":976},{"@type":"BreadcrumbList","@id":"https:\/\/www.nuevapescanova.com\/fr\/portfolio-item\/campana-navidad-2021-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.nuevapescanova.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Campagne de N\u00f6el 2021 (2)"}]},{"@type":"WebSite","@id":"https:\/\/www.nuevapescanova.com\/#website","url":"https:\/\/www.nuevapescanova.com\/","name":"Nueva Pescanova","description":"","publisher":{"@id":"https:\/\/www.nuevapescanova.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nuevapescanova.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.nuevapescanova.com\/#organization","name":"Nueva Pescanova","url":"https:\/\/www.nuevapescanova.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.nuevapescanova.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2023\/06\/Logo-Grupo-Nueva-Pescanova.jpg","contentUrl":"https:\/\/www.nuevapescanova.com\/nuevapescanova\/wp-content\/uploads\/2023\/06\/Logo-Grupo-Nueva-Pescanova.jpg","width":800,"height":398,"caption":"Nueva Pescanova"},"image":{"@id":"https:\/\/www.nuevapescanova.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/PescanovaCorp","https:\/\/www.linkedin.com\/company\/nuevapescanova\/?originalSubdomain=es"]}]}},"_links":{"self":[{"href":"https:\/\/www.nuevapescanova.com\/fr\/wp-json\/wp\/v2\/portfolio\/24346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nuevapescanova.com\/fr\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.nuevapescanova.com\/fr\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.nuevapescanova.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nuevapescanova.com\/fr\/wp-json\/wp\/v2\/comments?post=24346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nuevapescanova.com\/fr\/wp-json\/wp\/v2\/media\/24201"}],"wp:attachment":[{"href":"https:\/\/www.nuevapescanova.com\/fr\/wp-json\/wp\/v2\/media?parent=24346"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/www.nuevapescanova.com\/fr\/wp-json\/wp\/v2\/portfolio-types?post=24346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}